{"id":6150,"date":"2021-07-21T11:57:45","date_gmt":"2021-07-21T11:57:45","guid":{"rendered":"https:\/\/preview.wolfthemes.live\/app\/uploads\/sites\/39\/2021\/07\/clients_logo_light_03.png"},"modified":"2021-07-21T11:57:45","modified_gmt":"2021-07-21T11:57:45","slug":"clients_logo_light_03-2","status":"inherit","type":"attachment","link":"https:\/\/neonorma.lv\/lv\/clients_logo_light_03-2\/","title":{"rendered":"clients_logo_light_03"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-6150","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03.png'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-300x300.png 300w, https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-150x150.png 150w, https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03.png 500w, https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-400x400.png 400w, https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-100x100.png 100w, https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-290x290.png 290w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":500,"height":500,"file":"2021\/07\/clients_logo_light_03.png","filesize":17539,"sizes":{"medium":{"file":"clients_logo_light_03-300x300.png","width":300,"height":300,"filesize":17665,"mime_type":"image\/png","source_url":"https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-300x300.png"},"thumbnail":{"file":"clients_logo_light_03-150x150.png","width":150,"height":150,"filesize":7441,"mime_type":"image\/png","source_url":"https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-150x150.png"},"nu-photo":{"file":"clients_logo_light_03-500x500.png","width":500,"height":500,"filesize":24046,"mime_type":"image\/png","source_url":"https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-500x500.png"},"nu-masonry-small":{"file":"clients_logo_light_03-400x400.png","width":400,"height":400,"filesize":25309,"mime_type":"image\/png","source_url":"https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-400x400.png"},"wolf-core-photo":{"file":"clients_logo_light_03-500x500.png","width":500,"height":500,"filesize":24046,"mime_type":"image\/png","source_url":"https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-500x500.png"},"portfolio-thumb":{"file":"clients_logo_light_03-500x450.png","width":500,"height":450,"filesize":23623,"mime_type":"image\/png","source_url":"https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-500x450.png"},"portfolio-video-thumb":{"file":"clients_logo_light_03-480x360.png","width":480,"height":360,"filesize":30222,"mime_type":"image\/png","source_url":"https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-480x360.png"},"woocommerce_thumbnail":{"file":"clients_logo_light_03-300x300.png","width":300,"height":300,"filesize":17665,"uncropped":false,"mime_type":"image\/png","source_url":"https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-300x300.png"},"woocommerce_gallery_thumbnail":{"file":"clients_logo_light_03-100x100.png","width":100,"height":100,"filesize":4246,"mime_type":"image\/png","source_url":"https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-100x100.png"},"nu-related-post-thumbnail":{"file":"clients_logo_light_03-290x290.png","width":290,"height":290,"filesize":17130,"mime_type":"image\/png","source_url":"https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03-290x290.png"},"full":{"file":"clients_logo_light_03.png","width":500,"height":500,"mime_type":"image\/png","source_url":"https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/neonorma.lv\/wp-content\/uploads\/sites\/2\/2021\/07\/clients_logo_light_03.png","_links":{"self":[{"href":"https:\/\/neonorma.lv\/lv\/wp-json\/wp\/v2\/media\/6150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neonorma.lv\/lv\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/neonorma.lv\/lv\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/neonorma.lv\/lv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/neonorma.lv\/lv\/wp-json\/wp\/v2\/comments?post=6150"}]}}